{"id":160,"date":"2014-04-07T15:54:30","date_gmt":"2014-04-07T13:54:30","guid":{"rendered":"http:\/\/zweidesign.ch\/template\/_giulia\/?page_id=160"},"modified":"2016-10-17T16:23:35","modified_gmt":"2016-10-17T14:23:35","slug":"kontakt","status":"publish","type":"page","link":"https:\/\/giulia-steingruber.ch\/de\/kontakt\/","title":{"rendered":"Kontakt"},"content":{"rendered":"<p><strong>Kontakt<\/strong><\/p>\n<p><strong>Fanpost und Autogrammkarten<\/strong><br \/>\n(Bitte frankiertes C5 R\u00fcckantwortkuvert beilegen)<br \/>\nGiulia Steingruber<br \/>\nFanpost<br \/>\nArvenstrasse 3<br \/>\nCH-9200 Gossau<\/p>\n<p><strong>Sponsor-Management<\/strong><br \/>\nsportsemotion ag<br \/>\nKirchstrasse 27<br \/>\nCH-9400 Rorschach<br \/>\n+41 71 511 20 20<br \/>\n<a href=\"mailto:info@sportsemotion.ch\">info@sportsemotion.ch<\/a><\/p>\n<p><strong>Weitere Anfragen<\/strong><br \/>\nKurt Steingruber<br \/>\nArvenstrasse 3<br \/>\nCH-9200 Gossau<br \/>\nTelefon Gesch\u00e4ft +41 71 388 40 60<br \/>\nNatel +41 79 761 49 29<br \/>\n<a href=\"mailto:info@giulia-steingruber.ch\">info@giulia-steingruber.ch<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Kontakt Fanpost und Autogrammkarten (Bitte frankiertes C5 R\u00fcckantwortkuvert beilegen) Giulia Steingruber Fanpost Arvenstrasse 3 CH-9200 Gossau Sponsor-Management sportsemotion ag Kirchstrasse 27 CH-9400 Rorschach +41 71 511 20 20 info@sportsemotion.ch Weitere Anfragen Kurt Steingruber Arvenstrasse 3 CH-9200 Gossau Telefon Gesch\u00e4ft +41 71 388 40 60 Natel +41 79 761 49 29 info@giulia-steingruber.ch<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":8,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-160","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/pages\/160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/comments?post=160"}],"version-history":[{"count":7,"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/pages\/160\/revisions"}],"predecessor-version":[{"id":495,"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/pages\/160\/revisions\/495"}],"wp:attachment":[{"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/media?parent=160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}