{"id":288,"date":"2014-04-10T15:29:04","date_gmt":"2014-04-10T13:29:04","guid":{"rendered":"http:\/\/zweidesign.ch\/template\/_giulia\/?p=288"},"modified":"2014-04-27T10:57:32","modified_gmt":"2014-04-27T08:57:32","slug":"toller-start-in-die-wettkampfsaison-2014","status":"publish","type":"post","link":"https:\/\/giulia-steingruber.ch\/de\/2014\/04\/toller-start-in-die-wettkampfsaison-2014\/","title":{"rendered":"Toller Start in die Wettkampfsaison 2014"},"content":{"rendered":"<p>Toller Start in die Wettkampfsaison 2014. Mit dem dritten Schlussrang beim Weltcup A in Greensboro mit Pkt 57.332 bin ich sehr zufrieden. Hinter den beiden Amerikanerinnen Elisabeth Price und Brenna Dowell bin ich als beste Europ\u00e4erin in die Wettkampfsaison gestartet. Nur gerade zwei Zentel hinter Brenna Dowell trennen mich vom Silberplatz. Sprung 15.4, Barren 13.833, Balken 14.166 und Boden 13.933!<\/p>","protected":false},"excerpt":{"rendered":"<p>Toller Start in die Wettkampfsaison 2014. Mit dem dritten Schlussrang beim Weltcup A in Greensboro mit Pkt 57.332 bin ich sehr zufrieden. Hinter den beiden Amerikanerinnen Elisabeth Price und Brenna Dowell bin ich als beste Europ\u00e4erin in die Wettkampfsaison gestartet. Nur gerade zwei Zentel hinter Brenna Dowell trennen mich vom Silberplatz. Sprung 15.4, Barren 13.833, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-288","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/posts\/288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/comments?post=288"}],"version-history":[{"count":7,"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/posts\/288\/revisions"}],"predecessor-version":[{"id":479,"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/posts\/288\/revisions\/479"}],"wp:attachment":[{"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/media?parent=288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/categories?post=288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/tags?post=288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}