{"id":632,"date":"2014-05-15T19:44:19","date_gmt":"2014-05-15T17:44:19","guid":{"rendered":"http:\/\/giulia-steingruber.ch\/?p=632"},"modified":"2014-05-15T19:49:46","modified_gmt":"2014-05-15T17:49:46","slug":"em-sofia-team-qualifikation","status":"publish","type":"post","link":"https:\/\/giulia-steingruber.ch\/de\/2014\/05\/em-sofia-team-qualifikation\/","title":{"rendered":"EM Sofia Team Qualifikation"},"content":{"rendered":"<p>Eine sensationelle Mannschaftsleistung hat uns in der Qualifikation den sechsten Rang und somit die Finalteilnahme vom Samstag erm\u00f6glicht.\u00a0Gleichzeitig habe ich mich f\u00fcr den Balkenfinal, Bodenfinal und den Sprungfinal qualifiziert. Ich bin \u00fcbergl\u00fccklich und stolz auf die heutigen gezeigten Leistungen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Eine sensationelle Mannschaftsleistung hat uns in der Qualifikation den sechsten Rang und somit die Finalteilnahme vom Samstag erm\u00f6glicht.\u00a0Gleichzeitig habe ich mich f\u00fcr den Balkenfinal, Bodenfinal und den Sprungfinal qualifiziert. Ich bin \u00fcbergl\u00fccklich und stolz auf die heutigen gezeigten Leistungen.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-632","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/posts\/632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/comments?post=632"}],"version-history":[{"count":14,"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/posts\/632\/revisions"}],"predecessor-version":[{"id":647,"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/posts\/632\/revisions\/647"}],"wp:attachment":[{"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/media?parent=632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/categories?post=632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/giulia-steingruber.ch\/de\/wp-json\/wp\/v2\/tags?post=632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}